{"id":2673,"date":"2013-11-12T12:03:15","date_gmt":"2013-11-12T12:03:15","guid":{"rendered":"https:\/\/bon.de\/?post_type=product&#038;p=2673"},"modified":"2020-07-13T09:26:24","modified_gmt":"2020-07-13T09:26:24","slug":"sterile-einweg-corneafrasen-0-6mm-20-stuck-2","status":"publish","type":"product","link":"https:\/\/bon.de\/en\/product\/sterile-einweg-corneafrasen-0-6mm-20-stuck-2\/","title":{"rendered":"sterile Einweg-Corneafr\u00e4sen 0,6mm (20 St\u00fcck)"},"content":{"rendered":"<p>Einweg-Bohrer f\u00fcr Corneafr\u00e4sen, kurz<br \/>\n<br \/>passend f\u00fcr Modelle Grieshaber, Medical Workshop, H\u00fcbel, Heido<br \/>\n<br \/>St\u00e4rke: 0,6 mm<br \/>\n<br \/>L\u00e4nge: 24 mm<br \/>\n<br \/>Packung \u00e1 20 St\u00fcck<\/p>\n<p>\n<i>NICHT verwendbar mit den Modellen von Oculus, Algerbrush und Fischer<\/i><\/p>\n<p><i>Bitte beachten Sie, dass die R\u00fcckgabe von Sterilprodukten gem\u00e4\u00df MPG (Medizinproduktgesetz) ausgeschlossen ist.<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Einweg-Bohrer f\u00fcr Corneafr\u00e4sen, kurz passend f\u00fcr Modelle Grieshaber, Medical Workshop, H\u00fcbel, Heido St\u00e4rke: 0,6 mm L\u00e4nge: 24 mm Packung \u00e1 20 St\u00fcck NICHT verwendbar mit den Modellen von Oculus, Algerbrush und Fischer Bitte beachten Sie, dass die R\u00fcckgabe von Sterilprodukten gem\u00e4\u00df MPG (Medizinproduktgesetz) ausgeschlossen ist.<\/p>\n","protected":false},"featured_media":2674,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_manufacturers":[715],"product_brand":[],"product_cat":[185,199,367,117,129],"product_tag":[],"class_list":{"0":"post-2673","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bon-shop-2","7":"product_cat-disposables","8":"product_cat-disposable-burrs-for-rustring-remover","9":"product_cat-consumables","10":"product_cat-rustring-remover","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>sterile Einweg-Corneafr\u00e4sen 0,6mm (20 St\u00fcck)<\/title>\n<meta name=\"description\" content=\"Einweg-Bohrer f\u00fcr Corneafr\u00e4sen, kurz passend f\u00fcr Modelle Grieshaber, Medical Workshop, H\u00fcbel, Heido St\u00e4rke: 0,6 mm L\u00e4nge: 24 mm Packung \u00e1 20 St\u00fcck  NICHT verwendbar mit den Modellen von Oculus, Algerbrush und...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bon.de\/en\/product\/sterile-einweg-corneafrasen-0-6mm-20-stuck-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"sterile Einweg-Corneafr\u00e4sen 0,6mm (20 St\u00fcck)\" \/>\n<meta property=\"og:description\" content=\"Einweg-Bohrer f\u00fcr Corneafr\u00e4sen, kurz passend f\u00fcr Modelle Grieshaber, Medical Workshop, H\u00fcbel, Heido St\u00e4rke: 0,6 mm L\u00e4nge: 24 mm Packung \u00e1 20 St\u00fcck  NICHT verwendbar mit den Modellen von Oculus, Algerbrush und...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bon.de\/en\/product\/sterile-einweg-corneafrasen-0-6mm-20-stuck-2\/\" \/>\n<meta property=\"og:site_name\" content=\"bon Optic - Zukunft beginnt mit Qualit\u00e4t.\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-13T09:26:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bon.de\/wp-content\/uploads\/2013\/11\/products-einweg-cornea-bohrer-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"428\" \/>\n\t<meta property=\"og:image:height\" content=\"428\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bon.de\/en\/product\/sterile-einweg-corneafrasen-0-6mm-20-stuck-2\/\",\"url\":\"https:\/\/bon.de\/en\/product\/sterile-einweg-corneafrasen-0-6mm-20-stuck-2\/\",\"name\":\"sterile Einweg-Corneafr\u00e4sen 0,6mm (20 St\u00fcck)\",\"isPartOf\":{\"@id\":\"https:\/\/bon.de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bon.de\/en\/product\/sterile-einweg-corneafrasen-0-6mm-20-stuck-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bon.de\/en\/product\/sterile-einweg-corneafrasen-0-6mm-20-stuck-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bon.de\/wp-content\/uploads\/2013\/11\/products-einweg-cornea-bohrer-1.jpg\",\"datePublished\":\"2013-11-12T12:03:15+00:00\",\"dateModified\":\"2020-07-13T09:26:24+00:00\",\"description\":\"Einweg-Bohrer f\u00fcr Corneafr\u00e4sen, kurz passend f\u00fcr Modelle Grieshaber, Medical Workshop, H\u00fcbel, Heido St\u00e4rke: 0,6 mm L\u00e4nge: 24 mm Packung \u00e1 20 St\u00fcck NICHT verwendbar mit den Modellen von Oculus, Algerbrush und...\",\"breadcrumb\":{\"@id\":\"https:\/\/bon.de\/en\/product\/sterile-einweg-corneafrasen-0-6mm-20-stuck-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bon.de\/en\/product\/sterile-einweg-corneafrasen-0-6mm-20-stuck-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/bon.de\/en\/product\/sterile-einweg-corneafrasen-0-6mm-20-stuck-2\/#primaryimage\",\"url\":\"https:\/\/bon.de\/wp-content\/uploads\/2013\/11\/products-einweg-cornea-bohrer-1.jpg\",\"contentUrl\":\"https:\/\/bon.de\/wp-content\/uploads\/2013\/11\/products-einweg-cornea-bohrer-1.jpg\",\"width\":428,\"height\":428},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bon.de\/en\/product\/sterile-einweg-corneafrasen-0-6mm-20-stuck-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/bon.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/bon.de\/en\/shop-2-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"sterile Einweg-Corneafr\u00e4sen 0,6mm (20 St\u00fcck)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bon.de\/#website\",\"url\":\"https:\/\/bon.de\/\",\"name\":\"bon Optic - Zukunft beginnt mit Qualit\u00e4t.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/bon.de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bon.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bon.de\/#organization\",\"name\":\"bon Optic Vertriebsgesellschaft mbH\",\"url\":\"https:\/\/bon.de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/bon.de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bon.de\/wp-content\/uploads\/2021\/06\/bon-Logo_512x512px.png\",\"contentUrl\":\"https:\/\/bon.de\/wp-content\/uploads\/2021\/06\/bon-Logo_512x512px.png\",\"width\":512,\"height\":512,\"caption\":\"bon Optic Vertriebsgesellschaft mbH\"},\"image\":{\"@id\":\"https:\/\/bon.de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/bon-optic-vertriebsgesellschaft-mbh\/\",\"https:\/\/www.youtube.com\/channel\/UCSURhENDItKaH88bvn8LlcA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"sterile Einweg-Corneafr\u00e4sen 0,6mm (20 St\u00fcck)","description":"Einweg-Bohrer f\u00fcr Corneafr\u00e4sen, kurz passend f\u00fcr Modelle Grieshaber, Medical Workshop, H\u00fcbel, Heido St\u00e4rke: 0,6 mm L\u00e4nge: 24 mm Packung \u00e1 20 St\u00fcck  NICHT verwendbar mit den Modellen von Oculus, Algerbrush und...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bon.de\/en\/product\/sterile-einweg-corneafrasen-0-6mm-20-stuck-2\/","og_locale":"en_US","og_type":"article","og_title":"sterile Einweg-Corneafr\u00e4sen 0,6mm (20 St\u00fcck)","og_description":"Einweg-Bohrer f\u00fcr Corneafr\u00e4sen, kurz passend f\u00fcr Modelle Grieshaber, Medical Workshop, H\u00fcbel, Heido St\u00e4rke: 0,6 mm L\u00e4nge: 24 mm Packung \u00e1 20 St\u00fcck  NICHT verwendbar mit den Modellen von Oculus, Algerbrush und...","og_url":"https:\/\/bon.de\/en\/product\/sterile-einweg-corneafrasen-0-6mm-20-stuck-2\/","og_site_name":"bon Optic - Zukunft beginnt mit Qualit\u00e4t.","article_modified_time":"2020-07-13T09:26:24+00:00","og_image":[{"width":428,"height":428,"url":"https:\/\/bon.de\/wp-content\/uploads\/2013\/11\/products-einweg-cornea-bohrer-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bon.de\/en\/product\/sterile-einweg-corneafrasen-0-6mm-20-stuck-2\/","url":"https:\/\/bon.de\/en\/product\/sterile-einweg-corneafrasen-0-6mm-20-stuck-2\/","name":"sterile Einweg-Corneafr\u00e4sen 0,6mm (20 St\u00fcck)","isPartOf":{"@id":"https:\/\/bon.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bon.de\/en\/product\/sterile-einweg-corneafrasen-0-6mm-20-stuck-2\/#primaryimage"},"image":{"@id":"https:\/\/bon.de\/en\/product\/sterile-einweg-corneafrasen-0-6mm-20-stuck-2\/#primaryimage"},"thumbnailUrl":"https:\/\/bon.de\/wp-content\/uploads\/2013\/11\/products-einweg-cornea-bohrer-1.jpg","datePublished":"2013-11-12T12:03:15+00:00","dateModified":"2020-07-13T09:26:24+00:00","description":"Einweg-Bohrer f\u00fcr Corneafr\u00e4sen, kurz passend f\u00fcr Modelle Grieshaber, Medical Workshop, H\u00fcbel, Heido St\u00e4rke: 0,6 mm L\u00e4nge: 24 mm Packung \u00e1 20 St\u00fcck NICHT verwendbar mit den Modellen von Oculus, Algerbrush und...","breadcrumb":{"@id":"https:\/\/bon.de\/en\/product\/sterile-einweg-corneafrasen-0-6mm-20-stuck-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bon.de\/en\/product\/sterile-einweg-corneafrasen-0-6mm-20-stuck-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bon.de\/en\/product\/sterile-einweg-corneafrasen-0-6mm-20-stuck-2\/#primaryimage","url":"https:\/\/bon.de\/wp-content\/uploads\/2013\/11\/products-einweg-cornea-bohrer-1.jpg","contentUrl":"https:\/\/bon.de\/wp-content\/uploads\/2013\/11\/products-einweg-cornea-bohrer-1.jpg","width":428,"height":428},{"@type":"BreadcrumbList","@id":"https:\/\/bon.de\/en\/product\/sterile-einweg-corneafrasen-0-6mm-20-stuck-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bon.de\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/bon.de\/en\/shop-2-2\/"},{"@type":"ListItem","position":3,"name":"sterile Einweg-Corneafr\u00e4sen 0,6mm (20 St\u00fcck)"}]},{"@type":"WebSite","@id":"https:\/\/bon.de\/#website","url":"https:\/\/bon.de\/","name":"bon Optic - Zukunft beginnt mit Qualit\u00e4t.","description":"","publisher":{"@id":"https:\/\/bon.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bon.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/bon.de\/#organization","name":"bon Optic Vertriebsgesellschaft mbH","url":"https:\/\/bon.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bon.de\/#\/schema\/logo\/image\/","url":"https:\/\/bon.de\/wp-content\/uploads\/2021\/06\/bon-Logo_512x512px.png","contentUrl":"https:\/\/bon.de\/wp-content\/uploads\/2021\/06\/bon-Logo_512x512px.png","width":512,"height":512,"caption":"bon Optic Vertriebsgesellschaft mbH"},"image":{"@id":"https:\/\/bon.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/bon-optic-vertriebsgesellschaft-mbh\/","https:\/\/www.youtube.com\/channel\/UCSURhENDItKaH88bvn8LlcA"]}]}},"_links":{"self":[{"href":"https:\/\/bon.de\/en\/wp-json\/wp\/v2\/product\/2673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bon.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bon.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bon.de\/en\/wp-json\/wp\/v2\/comments?post=2673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bon.de\/en\/wp-json\/wp\/v2\/media\/2674"}],"wp:attachment":[{"href":"https:\/\/bon.de\/en\/wp-json\/wp\/v2\/media?parent=2673"}],"wp:term":[{"taxonomy":"product_manufacturers","embeddable":true,"href":"https:\/\/bon.de\/en\/wp-json\/wp\/v2\/product_manufacturers?post=2673"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bon.de\/en\/wp-json\/wp\/v2\/product_brand?post=2673"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bon.de\/en\/wp-json\/wp\/v2\/product_cat?post=2673"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bon.de\/en\/wp-json\/wp\/v2\/product_tag?post=2673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}